{"id":85032,"date":"2024-01-17T14:39:09","date_gmt":"2024-01-17T13:39:09","guid":{"rendered":"https:\/\/radiojatek-dev.elte.hu\/radiojatek\/85032\/"},"modified":"2026-05-26T18:52:38","modified_gmt":"2026-05-26T16:52:38","slug":"majusfa","status":"publish","type":"radioplay","link":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/85032\/","title":{"rendered":"M\u00e1jusfa"},"content":{"rendered":"<p>Mesterh\u00e1zi Lajos \u00e9s Sz\u00e1sz P\u00e9ter nagyoperettje<\/p>\n\n\n\n<p>Zen\u00e9j\u00e9t szerzette Kem\u00e9ny Egon<\/p>\n\n\n\n<p>Vez\u00e9nyel Majorossy Alad\u00e1r<\/p>\n\n\n\n<p>Km. a F\u00f6ld\u00e9nyi-k\u00f3rus<\/p>\n\n\n\n<p>Rendez\u0151: R\u00e1cz Gy\u00f6rgy<\/p>\n\n\n\n<p>K\u00e1ll\u00f3 Marika, a Technotex sz\u00f6v\u0151n\u0151je &#8211; Ferrari Violetta<\/p>\n\n\n\n<p>Ifj\u00famunk\u00e1sok &#8211; Horv\u00e1th Tivadar, D\u00e9k\u00e1ny L\u00e1szl\u00f3, R\u00e1tonyi R\u00f3bert, K\u00e1rp\u00e1ti Zolt\u00e1n<\/p>\n\n\n\n<p>Panda Antal szak\u00e1cs &#8211; Bilicsi Tivadar<\/p>\n\n\n\n<p>Studia-b\u00e1csi, \u00fcb. eln\u00f6k &#8211; Szigeti Jen\u0151<\/p>\n\n\n\n<p>Baksa, p\u00e1rttitk\u00e1r &#8211; Szak\u00e1cs Mikl\u00f3s<\/p>\n\n\n\n<p>n\u00e9pi koll\u00e9gist\u00e1k &#8211; P\u00e1los Gy\u00f6rgy, Kardos Magda, Hlatky Edit, Parragh \u00c9va<\/p>\n\n\n\n<p>Konok Teri, m\u0171egyetemista &#8211; Ruttkay \u00c9va<\/p>\n\n\n\n<p>Samu, kukta &#8211; Feh\u00e9regyh\u00e1zi Tibor <\/p>\n\n\n\n<p>Bad\u00e1cs, h\u00e1zmester &#8211; Bal\u00f3 Elem\u00e9r<\/p>\n\n\n\n<p>Ujs\u00e1g\u00edr\u00f3 &#8211; Gy\u0151z\u0151 L\u00e1szl\u00f3<\/p>\n\n\n\n<p>&#8221;  <\/p>\n\n\n\n<p>1949. m\u00e1jus 1., K 20.50-22.00 R\u00e1di\u00f3t a dolgoz\u00f3knak<\/p>\n\n\n\n<p>1974. december 14. A M\u00e1jusf\u00e1-val kezd\u0151d\u00f6tt.. A negyedsz\u00e1zados r\u00e1di\u00f3operett sz\u00fclet\u00e9s\u00e9nek \u00e9s els\u0151 ad\u00e1s\u00e1nak t\u00f6rt\u00e9nete<\/p>\n\n\n\n<p>&#8222;R\u00e9vai J\u00f3zsef ekkoriban a k\u00f6zhangulat jav\u00edt\u00e1sa \u00e9rdek\u00e9ben propon\u00e1lta, hogy a r\u00e1di\u00f3 karolja fel az operettet mint m\u0171fajt, \u00e9s sz\u00fclessenek \u00fagynevezett r\u00e1di\u00f3operettek. Az Irodalmi Oszt\u00e1ly k\u00e9t frissen bel\u00e9pett ifj\u00fa munkat\u00e1rsa, Mesterh\u00e1zy Lajos \u00e9s Sz\u00e1sz P\u00e9ter k\u00e9sz\u00edtette el Kem\u00e9ny Egon zen\u00e9j\u00e9vel az els\u0151 r\u00e1di\u00f3operettet M\u00e1jusfa c\u00edmmel, s ezzel megind\u00edtott\u00e1k a korszak \u00faj r\u00e1di\u00f3s m\u0171faj\u00e1t.&#8221; (<a href=\"https:\/\/adt.arcanum.com\/en\/view\/Multunk_2005\/?query=%22a+pr%C3%B3zai+oszt%C3%A1ly+vezet%C5%91je%22&amp;pg=798&amp;layout=l\">Forr\u00e1s<\/a>)<\/p>","protected":false},"excerpt":{"rendered":"<p>Mesterh\u00e1zi Lajos \u00e9s Sz\u00e1sz P\u00e9ter nagyoperettje Zen\u00e9j\u00e9t szerzette Kem\u00e9ny Egon Vez\u00e9nyel Majorossy Alad\u00e1r Km. a F\u00f6ld\u00e9nyi-k\u00f3rus Rendez\u0151: R\u00e1cz Gy\u00f6rgy K\u00e1ll\u00f3 Marika, a Technotex sz\u00f6v\u0151n\u0151je &#8211; Ferrari Violetta Ifj\u00famunk\u00e1sok &#8211; Horv\u00e1th Tivadar, D\u00e9k\u00e1ny L\u00e1szl\u00f3, R\u00e1tonyi R\u00f3bert, K\u00e1rp\u00e1ti Zolt\u00e1n Panda Antal szak\u00e1cs &#8211; Bilicsi Tivadar Studia-b\u00e1csi, \u00fcb. eln\u00f6k &#8211; Szigeti Jen\u0151 Baksa, p\u00e1rttitk\u00e1r &#8211; Szak\u00e1cs Mikl\u00f3s n\u00e9pi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","radioplay_author":[7480,8579,11179],"radioplay_director":[7482,7594],"radioplay_actor":[21257,19765,16965,17590,16848,18661],"radioplay_award":[],"radioplay_category":[],"radioplay_translator":[],"radioplay_dramaturge":[],"radioplay_radio_applier":[],"radioplay_codirector":[],"radioplay_editor":[],"radioplay_composer":[16015],"radioplay_music_editor":[],"radioplay_music_director":[],"radioplay_technical_colleague":[],"radioplay_music_performer":[21580],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e1jusfa -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/85032\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1jusfa -\" \/>\n<meta property=\"og:description\" content=\"Mesterh\u00e1zi Lajos \u00e9s Sz\u00e1sz P\u00e9ter nagyoperettje Zen\u00e9j\u00e9t szerzette Kem\u00e9ny Egon Vez\u00e9nyel Majorossy Alad\u00e1r Km. a F\u00f6ld\u00e9nyi-k\u00f3rus Rendez\u0151: R\u00e1cz Gy\u00f6rgy K\u00e1ll\u00f3 Marika, a Technotex sz\u00f6v\u0151n\u0151je &#8211; Ferrari Violetta Ifj\u00famunk\u00e1sok &#8211; Horv\u00e1th Tivadar, D\u00e9k\u00e1ny L\u00e1szl\u00f3, R\u00e1tonyi R\u00f3bert, K\u00e1rp\u00e1ti Zolt\u00e1n Panda Antal szak\u00e1cs &#8211; Bilicsi Tivadar Studia-b\u00e1csi, \u00fcb. eln\u00f6k &#8211; Szigeti Jen\u0151 Baksa, p\u00e1rttitk\u00e1r &#8211; Szak\u00e1cs Mikl\u00f3s n\u00e9pi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/85032\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T16:52:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/\",\"name\":\"M\u00e1jusfa -\",\"isPartOf\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\"},\"datePublished\":\"2024-01-17T13:39:09+00:00\",\"dateModified\":\"2026-05-26T16:52:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/radiojatek.elte.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1jusfa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"name\":\"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151\",\"description\":\"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa\",\"publisher\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\"},\"alternateName\":\"Hangj\u00e1t\u00e9k-keres\u0151\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiojatek.elte.hu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\",\"name\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"contentUrl\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"width\":512,\"height\":512,\"caption\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\"},\"image\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1jusfa -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/85032\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e1jusfa -","og_description":"Mesterh\u00e1zi Lajos \u00e9s Sz\u00e1sz P\u00e9ter nagyoperettje Zen\u00e9j\u00e9t szerzette Kem\u00e9ny Egon Vez\u00e9nyel Majorossy Alad\u00e1r Km. a F\u00f6ld\u00e9nyi-k\u00f3rus Rendez\u0151: R\u00e1cz Gy\u00f6rgy K\u00e1ll\u00f3 Marika, a Technotex sz\u00f6v\u0151n\u0151je &#8211; Ferrari Violetta Ifj\u00famunk\u00e1sok &#8211; Horv\u00e1th Tivadar, D\u00e9k\u00e1ny L\u00e1szl\u00f3, R\u00e1tonyi R\u00f3bert, K\u00e1rp\u00e1ti Zolt\u00e1n Panda Antal szak\u00e1cs &#8211; Bilicsi Tivadar Studia-b\u00e1csi, \u00fcb. eln\u00f6k &#8211; Szigeti Jen\u0151 Baksa, p\u00e1rttitk\u00e1r &#8211; Szak\u00e1cs Mikl\u00f3s n\u00e9pi [&hellip;]","og_url":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/85032\/","article_modified_time":"2026-05-26T16:52:38+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/","url":"https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/","name":"M\u00e1jusfa -","isPartOf":{"@id":"https:\/\/radiojatek.elte.hu\/#website"},"datePublished":"2024-01-17T13:39:09+00:00","dateModified":"2026-05-26T16:52:38+00:00","breadcrumb":{"@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/85032\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radiojatek.elte.hu\/"},{"@type":"ListItem","position":2,"name":"M\u00e1jusfa"}]},{"@type":"WebSite","@id":"https:\/\/radiojatek.elte.hu\/#website","url":"https:\/\/radiojatek.elte.hu\/","name":"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151","description":"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa","publisher":{"@id":"https:\/\/radiojatek.elte.hu\/#organization"},"alternateName":"Hangj\u00e1t\u00e9k-keres\u0151","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiojatek.elte.hu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/radiojatek.elte.hu\/#organization","name":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis","url":"https:\/\/radiojatek.elte.hu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/","url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","contentUrl":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","width":512,"height":512,"caption":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis"},"image":{"@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/85032"}],"collection":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay"}],"about":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/types\/radioplay"}],"author":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/comments?post=85032"}],"version-history":[{"count":7,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/85032\/revisions"}],"predecessor-version":[{"id":127029,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/85032\/revisions\/127029"}],"wp:attachment":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/media?parent=85032"}],"wp:term":[{"taxonomy":"radioplay_author","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_author?post=85032"},{"taxonomy":"radioplay_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_director?post=85032"},{"taxonomy":"radioplay_actor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_actor?post=85032"},{"taxonomy":"radioplay_award","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_award?post=85032"},{"taxonomy":"radioplay_category","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_category?post=85032"},{"taxonomy":"radioplay_translator","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_translator?post=85032"},{"taxonomy":"radioplay_dramaturge","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_dramaturge?post=85032"},{"taxonomy":"radioplay_radio_applier","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_radio_applier?post=85032"},{"taxonomy":"radioplay_codirector","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_codirector?post=85032"},{"taxonomy":"radioplay_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_editor?post=85032"},{"taxonomy":"radioplay_composer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_composer?post=85032"},{"taxonomy":"radioplay_music_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_editor?post=85032"},{"taxonomy":"radioplay_music_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_director?post=85032"},{"taxonomy":"radioplay_technical_colleague","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_technical_colleague?post=85032"},{"taxonomy":"radioplay_music_performer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_performer?post=85032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}