{"id":32413,"date":"2021-09-29T10:19:08","date_gmt":"2021-09-29T08:19:08","guid":{"rendered":"http:\/\/radiojatek.tld\/radiojatek\/32413\/"},"modified":"2026-05-26T18:47:30","modified_gmt":"2026-05-26T16:47:30","slug":"a-varazsszemuveg-2","status":"publish","type":"radioplay","link":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/32413\/","title":{"rendered":"A var\u00e1zsszem\u00fcveg"},"content":{"rendered":"<p>Cili Wethekam reg\u00e9ny\u00e9t G. Beke Margit ford\u00edt\u00e1sa alapj\u00e1n r\u00e1di\u00f3ra alkalmazta: G\u00f6dr\u00f6s J\u00falia<\/p>\n<p>Szerepl\u0151k:<\/p>\n<p>Narr\u00e1tor &#8211; Fodor Tam\u00e1s,<\/p>\n<p>Ilse &#8211; Kucs\u00e9ber Anik\u00f3,<\/p>\n<p>Herta &#8211; R\u00e9vai Judit,<\/p>\n<p>Herta apja &#8211; Turgonyi P\u00e1l,<\/p>\n<p>Herta anyja &#8211; D\u00e1vid \u00c1gnes,<\/p>\n<p>Tomi &#8211; N\u00e9meth L\u00e1szl\u00f3,<\/p>\n<p>Timi apja &#8211; Buss Gyula,<\/p>\n<p>Tan\u00edt\u00f3 &#8211; Szigeti Andr\u00e1s<\/p>\n<p>Zenei munkat\u00e1rs: Zsed\u00e9nyi Erzs\u00e9bet<\/p>\n<p>Dramaturg: Hackl Jol\u00e1n<\/p>\n<p>Rendez\u0151: V\u00e1rkonyi G\u00e1bor<\/p>\n<p>33 perc<\/p>\n<p>Bemutatva: 1977. december 19. 10:05, Kossuth, Ifj\u00fas\u00e1gi r\u00e1di\u00f3<\/p>","protected":false},"excerpt":{"rendered":"<p>Cili Wethekam reg\u00e9ny\u00e9t G. Beke Margit ford\u00edt\u00e1sa alapj\u00e1n r\u00e1di\u00f3ra alkalmazta: G\u00f6dr\u00f6s J\u00falia Szerepl\u0151k: Narr\u00e1tor &#8211; Fodor Tam\u00e1s, Ilse &#8211; Kucs\u00e9ber Anik\u00f3, Herta &#8211; R\u00e9vai Judit, Herta apja &#8211; Turgonyi P\u00e1l, Herta anyja &#8211; D\u00e1vid \u00c1gnes, Tomi &#8211; N\u00e9meth L\u00e1szl\u00f3, Timi apja &#8211; Buss Gyula, Tan\u00edt\u00f3 &#8211; Szigeti Andr\u00e1s Zenei munkat\u00e1rs: Zsed\u00e9nyi Erzs\u00e9bet Dramaturg: Hackl Jol\u00e1n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","radioplay_author":[19372],"radioplay_director":[7482,9576],"radioplay_actor":[15715,16146,33996,25181,21301,16970],"radioplay_award":[],"radioplay_category":[15630],"radioplay_translator":[],"radioplay_dramaturge":[13566],"radioplay_radio_applier":[9779],"radioplay_codirector":[],"radioplay_editor":[],"radioplay_composer":[],"radioplay_music_editor":[17576],"radioplay_music_director":[],"radioplay_technical_colleague":[],"radioplay_music_performer":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A var\u00e1zsszem\u00fcveg -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/32413\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A var\u00e1zsszem\u00fcveg -\" \/>\n<meta property=\"og:description\" content=\"Cili Wethekam reg\u00e9ny\u00e9t G. Beke Margit ford\u00edt\u00e1sa alapj\u00e1n r\u00e1di\u00f3ra alkalmazta: G\u00f6dr\u00f6s J\u00falia Szerepl\u0151k: Narr\u00e1tor &#8211; Fodor Tam\u00e1s, Ilse &#8211; Kucs\u00e9ber Anik\u00f3, Herta &#8211; R\u00e9vai Judit, Herta apja &#8211; Turgonyi P\u00e1l, Herta anyja &#8211; D\u00e1vid \u00c1gnes, Tomi &#8211; N\u00e9meth L\u00e1szl\u00f3, Timi apja &#8211; Buss Gyula, Tan\u00edt\u00f3 &#8211; Szigeti Andr\u00e1s Zenei munkat\u00e1rs: Zsed\u00e9nyi Erzs\u00e9bet Dramaturg: Hackl Jol\u00e1n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/32413\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T16:47:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/\",\"name\":\"A var\u00e1zsszem\u00fcveg -\",\"isPartOf\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\"},\"datePublished\":\"2021-09-29T08:19:08+00:00\",\"dateModified\":\"2026-05-26T16:47:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/radiojatek.elte.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A var\u00e1zsszem\u00fcveg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"name\":\"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151\",\"description\":\"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa\",\"publisher\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\"},\"alternateName\":\"Hangj\u00e1t\u00e9k-keres\u0151\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiojatek.elte.hu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\",\"name\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"contentUrl\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"width\":512,\"height\":512,\"caption\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\"},\"image\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A var\u00e1zsszem\u00fcveg -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/32413\/","og_locale":"en_US","og_type":"article","og_title":"A var\u00e1zsszem\u00fcveg -","og_description":"Cili Wethekam reg\u00e9ny\u00e9t G. Beke Margit ford\u00edt\u00e1sa alapj\u00e1n r\u00e1di\u00f3ra alkalmazta: G\u00f6dr\u00f6s J\u00falia Szerepl\u0151k: Narr\u00e1tor &#8211; Fodor Tam\u00e1s, Ilse &#8211; Kucs\u00e9ber Anik\u00f3, Herta &#8211; R\u00e9vai Judit, Herta apja &#8211; Turgonyi P\u00e1l, Herta anyja &#8211; D\u00e1vid \u00c1gnes, Tomi &#8211; N\u00e9meth L\u00e1szl\u00f3, Timi apja &#8211; Buss Gyula, Tan\u00edt\u00f3 &#8211; Szigeti Andr\u00e1s Zenei munkat\u00e1rs: Zsed\u00e9nyi Erzs\u00e9bet Dramaturg: Hackl Jol\u00e1n [&hellip;]","og_url":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/32413\/","article_modified_time":"2026-05-26T16:47:30+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/","url":"https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/","name":"A var\u00e1zsszem\u00fcveg -","isPartOf":{"@id":"https:\/\/radiojatek.elte.hu\/#website"},"datePublished":"2021-09-29T08:19:08+00:00","dateModified":"2026-05-26T16:47:30+00:00","breadcrumb":{"@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/32413\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radiojatek.elte.hu\/"},{"@type":"ListItem","position":2,"name":"A var\u00e1zsszem\u00fcveg"}]},{"@type":"WebSite","@id":"https:\/\/radiojatek.elte.hu\/#website","url":"https:\/\/radiojatek.elte.hu\/","name":"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151","description":"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa","publisher":{"@id":"https:\/\/radiojatek.elte.hu\/#organization"},"alternateName":"Hangj\u00e1t\u00e9k-keres\u0151","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiojatek.elte.hu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/radiojatek.elte.hu\/#organization","name":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis","url":"https:\/\/radiojatek.elte.hu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/","url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","contentUrl":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","width":512,"height":512,"caption":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis"},"image":{"@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/32413"}],"collection":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay"}],"about":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/types\/radioplay"}],"author":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/comments?post=32413"}],"version-history":[{"count":3,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/32413\/revisions"}],"predecessor-version":[{"id":77092,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/32413\/revisions\/77092"}],"wp:attachment":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/media?parent=32413"}],"wp:term":[{"taxonomy":"radioplay_author","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_author?post=32413"},{"taxonomy":"radioplay_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_director?post=32413"},{"taxonomy":"radioplay_actor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_actor?post=32413"},{"taxonomy":"radioplay_award","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_award?post=32413"},{"taxonomy":"radioplay_category","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_category?post=32413"},{"taxonomy":"radioplay_translator","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_translator?post=32413"},{"taxonomy":"radioplay_dramaturge","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_dramaturge?post=32413"},{"taxonomy":"radioplay_radio_applier","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_radio_applier?post=32413"},{"taxonomy":"radioplay_codirector","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_codirector?post=32413"},{"taxonomy":"radioplay_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_editor?post=32413"},{"taxonomy":"radioplay_composer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_composer?post=32413"},{"taxonomy":"radioplay_music_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_editor?post=32413"},{"taxonomy":"radioplay_music_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_director?post=32413"},{"taxonomy":"radioplay_technical_colleague","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_technical_colleague?post=32413"},{"taxonomy":"radioplay_music_performer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_performer?post=32413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}