{"id":29753,"date":"2021-09-29T07:13:53","date_gmt":"2021-09-29T05:13:53","guid":{"rendered":"http:\/\/radiojatek.tld\/radiojatek\/29753\/"},"modified":"2025-10-26T16:01:42","modified_gmt":"2025-10-26T15:01:42","slug":"pajkos-diakok","status":"publish","type":"radioplay","link":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/29753\/","title":{"rendered":"Pajkos di\u00e1kok"},"content":{"rendered":"<p>Egyfelvon\u00e1sos dalj\u00e1t\u00e9k<\/p>\n<p>Sz\u00f6veg\u00e9t \u00edrta: Josef Braun<\/p>\n<p>Supp\u00e9 m\u0171ve alapj\u00e1n<\/p>\n<p>Egyfelvon\u00e1sos dalj\u00e1t\u00e9k.<\/p>\n<p>Ford\u00edtotta, r\u00e1di\u00f3ra \u00e1tdolgozta: Innoncent Vincze Ern\u0151<\/p>\n<p>Vez\u00e9nyel: Breitner Tam\u00e1s<\/p>\n<p>K\u00f6zrem\u0171k\u00f6dik: Az MRT szimfonikus zenekara \u00e9s \u00e9nekkara<\/p>\n<p>Karigazgat\u00f3: Sapszon Ferenc<\/p>\n<p>Zenei rendez\u0151: J\u00e1rf\u00e1s Tam\u00e1s<\/p>\n<p>Rendez\u0151: dr. Cser\u00e9s Mikl\u00f3s<\/p>\n<p>Szereposzt\u00e1s: V\u00e1rhelyi Endre; Basilides Zolt\u00e1n (Geier, t\u0151kep\u00e9nzes), Szirmay M\u00e1rta; B\u00e9res Ilona (L\u00e9ni, pinc\u00e9rl\u00e1ny), Erd\u00e9sz Zsuzsa, S\u00f3lyom Ildik\u00f3 (Lizi, a h\u00faga), Barha Alfonz, Somogyv\u00e1ri P\u00e1l (Anton, asztalosleg\u00e9ny), Bende Zsolt, M\u00e9cs K\u00e1roly, Palcs\u00f3 S\u00e1ndor, M\u00e1rkus L\u00e1szl\u00f3 (Brand \u00e9s Fleck di\u00e1kok), Cs\u00e1k\u00e1nyi L\u00e1szl\u00f3 (Kocsm\u00e1ros), Bak\u00f3 M\u00e1rta; K\u0151m\u0171ves Erzsi, V\u00e1nday Margit (3n\u00e9ni), Verdes Tam\u00e1s,Vereb\u00e9lyi Iv\u00e1n (2 di\u00e1k)<\/p>\n<p>1966. december 28., K 19.30-20.39<\/p>\n<p>1974. augusztus 30., P 20.28<\/p>\n<p>1975. \u00e1prilis 27. Vas\u00e1rnap, Pet\u0151fi R\u00e1di\u00f3 9:12<\/p>\n<p>1976. janu\u00e1r 13. kedd 21.01<\/p>\n<p>1979. j\u00fan. 5. 12:50-13:59 Kossuth (69 perc)<\/p>\n<p>1987. 01. 13. 21.27,\u00a0 Pet\u0151fi 70 perc<\/p>\n<p>1991. j\u00fanius 10. Pet\u0151fi, 9.28<\/p>","protected":false},"excerpt":{"rendered":"<p>Egyfelvon\u00e1sos dalj\u00e1t\u00e9k Sz\u00f6veg\u00e9t \u00edrta: Josef Braun Supp\u00e9 m\u0171ve alapj\u00e1n Egyfelvon\u00e1sos dalj\u00e1t\u00e9k. Ford\u00edtotta, r\u00e1di\u00f3ra \u00e1tdolgozta: Innoncent Vincze Ern\u0151 Vez\u00e9nyel: Breitner Tam\u00e1s K\u00f6zrem\u0171k\u00f6dik: Az MRT szimfonikus zenekara \u00e9s \u00e9nekkara Karigazgat\u00f3: Sapszon Ferenc Zenei rendez\u0151: J\u00e1rf\u00e1s Tam\u00e1s Rendez\u0151: dr. Cser\u00e9s Mikl\u00f3s Szereposzt\u00e1s: V\u00e1rhelyi Endre; Basilides Zolt\u00e1n (Geier, t\u0151kep\u00e9nzes), Szirmay M\u00e1rta; B\u00e9res Ilona (L\u00e9ni, pinc\u00e9rl\u00e1ny), Erd\u00e9sz Zsuzsa, S\u00f3lyom Ildik\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","radioplay_author":[8759,13315],"radioplay_director":[7667,7482],"radioplay_actor":[15760,16944,16164,16193,29242,16140,15736,30066,18038,19945,30085,17589,16238],"radioplay_award":[],"radioplay_category":[],"radioplay_translator":[20829],"radioplay_dramaturge":[],"radioplay_radio_applier":[9341],"radioplay_codirector":[],"radioplay_editor":[],"radioplay_composer":[19618],"radioplay_music_editor":[],"radioplay_music_director":[17853],"radioplay_technical_colleague":[],"radioplay_music_performer":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pajkos di\u00e1kok -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/29753\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pajkos di\u00e1kok -\" \/>\n<meta property=\"og:description\" content=\"Egyfelvon\u00e1sos dalj\u00e1t\u00e9k Sz\u00f6veg\u00e9t \u00edrta: Josef Braun Supp\u00e9 m\u0171ve alapj\u00e1n Egyfelvon\u00e1sos dalj\u00e1t\u00e9k. Ford\u00edtotta, r\u00e1di\u00f3ra \u00e1tdolgozta: Innoncent Vincze Ern\u0151 Vez\u00e9nyel: Breitner Tam\u00e1s K\u00f6zrem\u0171k\u00f6dik: Az MRT szimfonikus zenekara \u00e9s \u00e9nekkara Karigazgat\u00f3: Sapszon Ferenc Zenei rendez\u0151: J\u00e1rf\u00e1s Tam\u00e1s Rendez\u0151: dr. Cser\u00e9s Mikl\u00f3s Szereposzt\u00e1s: V\u00e1rhelyi Endre; Basilides Zolt\u00e1n (Geier, t\u0151kep\u00e9nzes), Szirmay M\u00e1rta; B\u00e9res Ilona (L\u00e9ni, pinc\u00e9rl\u00e1ny), Erd\u00e9sz Zsuzsa, S\u00f3lyom Ildik\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/29753\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-26T15:01:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/\",\"name\":\"Pajkos di\u00e1kok -\",\"isPartOf\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\"},\"datePublished\":\"2021-09-29T05:13:53+00:00\",\"dateModified\":\"2025-10-26T15:01:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/radiojatek.elte.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pajkos di\u00e1kok\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"name\":\"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151\",\"description\":\"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa\",\"publisher\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\"},\"alternateName\":\"Hangj\u00e1t\u00e9k-keres\u0151\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiojatek.elte.hu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\",\"name\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"contentUrl\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"width\":512,\"height\":512,\"caption\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\"},\"image\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pajkos di\u00e1kok -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/29753\/","og_locale":"en_US","og_type":"article","og_title":"Pajkos di\u00e1kok -","og_description":"Egyfelvon\u00e1sos dalj\u00e1t\u00e9k Sz\u00f6veg\u00e9t \u00edrta: Josef Braun Supp\u00e9 m\u0171ve alapj\u00e1n Egyfelvon\u00e1sos dalj\u00e1t\u00e9k. Ford\u00edtotta, r\u00e1di\u00f3ra \u00e1tdolgozta: Innoncent Vincze Ern\u0151 Vez\u00e9nyel: Breitner Tam\u00e1s K\u00f6zrem\u0171k\u00f6dik: Az MRT szimfonikus zenekara \u00e9s \u00e9nekkara Karigazgat\u00f3: Sapszon Ferenc Zenei rendez\u0151: J\u00e1rf\u00e1s Tam\u00e1s Rendez\u0151: dr. Cser\u00e9s Mikl\u00f3s Szereposzt\u00e1s: V\u00e1rhelyi Endre; Basilides Zolt\u00e1n (Geier, t\u0151kep\u00e9nzes), Szirmay M\u00e1rta; B\u00e9res Ilona (L\u00e9ni, pinc\u00e9rl\u00e1ny), Erd\u00e9sz Zsuzsa, S\u00f3lyom Ildik\u00f3 [&hellip;]","og_url":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/29753\/","article_modified_time":"2025-10-26T15:01:42+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/","url":"https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/","name":"Pajkos di\u00e1kok -","isPartOf":{"@id":"https:\/\/radiojatek.elte.hu\/#website"},"datePublished":"2021-09-29T05:13:53+00:00","dateModified":"2025-10-26T15:01:42+00:00","breadcrumb":{"@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/29753\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radiojatek.elte.hu\/"},{"@type":"ListItem","position":2,"name":"Pajkos di\u00e1kok"}]},{"@type":"WebSite","@id":"https:\/\/radiojatek.elte.hu\/#website","url":"https:\/\/radiojatek.elte.hu\/","name":"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151","description":"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa","publisher":{"@id":"https:\/\/radiojatek.elte.hu\/#organization"},"alternateName":"Hangj\u00e1t\u00e9k-keres\u0151","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiojatek.elte.hu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/radiojatek.elte.hu\/#organization","name":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis","url":"https:\/\/radiojatek.elte.hu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/","url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","contentUrl":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","width":512,"height":512,"caption":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis"},"image":{"@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/29753"}],"collection":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay"}],"about":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/types\/radioplay"}],"author":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/comments?post=29753"}],"version-history":[{"count":8,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/29753\/revisions"}],"predecessor-version":[{"id":86438,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/29753\/revisions\/86438"}],"wp:attachment":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/media?parent=29753"}],"wp:term":[{"taxonomy":"radioplay_author","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_author?post=29753"},{"taxonomy":"radioplay_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_director?post=29753"},{"taxonomy":"radioplay_actor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_actor?post=29753"},{"taxonomy":"radioplay_award","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_award?post=29753"},{"taxonomy":"radioplay_category","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_category?post=29753"},{"taxonomy":"radioplay_translator","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_translator?post=29753"},{"taxonomy":"radioplay_dramaturge","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_dramaturge?post=29753"},{"taxonomy":"radioplay_radio_applier","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_radio_applier?post=29753"},{"taxonomy":"radioplay_codirector","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_codirector?post=29753"},{"taxonomy":"radioplay_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_editor?post=29753"},{"taxonomy":"radioplay_composer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_composer?post=29753"},{"taxonomy":"radioplay_music_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_editor?post=29753"},{"taxonomy":"radioplay_music_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_director?post=29753"},{"taxonomy":"radioplay_technical_colleague","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_technical_colleague?post=29753"},{"taxonomy":"radioplay_music_performer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_performer?post=29753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}