{"id":27908,"date":"2021-09-28T21:58:16","date_gmt":"2021-09-28T19:58:16","guid":{"rendered":"http:\/\/radiojatek.tld\/radiojatek\/27908\/"},"modified":"2026-05-26T18:32:00","modified_gmt":"2026-05-26T16:32:00","slug":"karneval","status":"publish","type":"radioplay","link":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/27908\/","title":{"rendered":"Karnev\u00e1l"},"content":{"rendered":"<p>1950. 05. 31. Kossuth 22.30 70 perc<\/p>\n<p>Robert Schumann zen\u00e9s \u00e9letrajza. Hangfelv\u00e9tel.<\/p>\n<p>\u00cdrta: Krist\u00f3f K\u00e1roly<\/p>\n<p>Rendezte: Sz\u00e9csi Ferenc<\/p>\n<p>K\u00f6zrem\u0171k\u00f6dik: Seb\u0151k Gy\u00f6rgy (zongora)<\/p>\n<p>Szereposzt\u00e1s:<\/p>\n<p>Robert Schumann \u2013 Ungv\u00e1ri L\u00e1szl\u00f3<\/p>\n<p>Fridrich Wieck \u2013 R\u00e1tkay M\u00e1rton<\/p>\n<p>Kl\u00e1ra, a le\u00e1nya- Ruttkay \u00c9va<\/p>\n<p>Ernestine Flecken \u2013 B\u00e1nki Zsuzsa<\/p>\n<p>Hasslinger, zenem\u0171kiad\u00f3 \u2013 Justh Gyula<\/p>\n<p>Liszt Ferenc \u2013 Ungv\u00e1ri L\u00e1szl\u00f3<\/p>\n<p>Knorr, Schumann bar\u00e1tja \u2013 Telegdi Polg\u00e1r Istv\u00e1n<\/p>\n<p>Orvos \u2013 Szegedi Szab\u00f3 Istv\u00e1n<\/p>\n<p>N\u0151v\u00e9r \u2013 E\u0151ry Kat\u00f3<\/p>\n<p>\u00dczemi el\u0151ad\u00f3- Som Istv\u00e1n<\/p>\n<p>1. hal\u00e1sz \u2013 M\u00e1rkus Ferenc<\/p>\n<p>2. hal\u00e1sz &#8211; Leviczky Andor<\/p>\n<p>1. hang &#8211; Szalay K\u00e1roly<\/p>\n<p>2. hang &#8211; Nizsinszky Tamara<\/p>\n<p>3. hang &#8211; Jo\u00f3 L\u00e1szl\u00f3<\/p>\n<p>4. hang &#8211; T\u00e9ry Arv\u00e9d<\/p>\n<p>szobal\u00e1ny &#8211; H\u00f3dosi M\u00e1ria<\/p>","protected":false},"excerpt":{"rendered":"<p>1950. 05. 31. Kossuth 22.30 70 perc Robert Schumann zen\u00e9s \u00e9letrajza. Hangfelv\u00e9tel. \u00cdrta: Krist\u00f3f K\u00e1roly Rendezte: Sz\u00e9csi Ferenc K\u00f6zrem\u0171k\u00f6dik: Seb\u0151k Gy\u00f6rgy (zongora) Szereposzt\u00e1s: Robert Schumann \u2013 Ungv\u00e1ri L\u00e1szl\u00f3 Fridrich Wieck \u2013 R\u00e1tkay M\u00e1rton Kl\u00e1ra, a le\u00e1nya- Ruttkay \u00c9va Ernestine Flecken \u2013 B\u00e1nki Zsuzsa Hasslinger, zenem\u0171kiad\u00f3 \u2013 Justh Gyula Liszt Ferenc \u2013 Ungv\u00e1ri L\u00e1szl\u00f3 Knorr, Schumann [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","radioplay_author":[9337,7480],"radioplay_director":[7482,8401],"radioplay_actor":[16991,35032,18053,27704,32444,19057,32408,26708,22300,32593,18474,35033,26664],"radioplay_award":[],"radioplay_category":[],"radioplay_translator":[],"radioplay_dramaturge":[15022],"radioplay_radio_applier":[],"radioplay_codirector":[],"radioplay_editor":[],"radioplay_composer":[],"radioplay_music_editor":[],"radioplay_music_director":[],"radioplay_technical_colleague":[],"radioplay_music_performer":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Karnev\u00e1l -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/27908\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karnev\u00e1l -\" \/>\n<meta property=\"og:description\" content=\"1950. 05. 31. Kossuth 22.30 70 perc Robert Schumann zen\u00e9s \u00e9letrajza. Hangfelv\u00e9tel. \u00cdrta: Krist\u00f3f K\u00e1roly Rendezte: Sz\u00e9csi Ferenc K\u00f6zrem\u0171k\u00f6dik: Seb\u0151k Gy\u00f6rgy (zongora) Szereposzt\u00e1s: Robert Schumann \u2013 Ungv\u00e1ri L\u00e1szl\u00f3 Fridrich Wieck \u2013 R\u00e1tkay M\u00e1rton Kl\u00e1ra, a le\u00e1nya- Ruttkay \u00c9va Ernestine Flecken \u2013 B\u00e1nki Zsuzsa Hasslinger, zenem\u0171kiad\u00f3 \u2013 Justh Gyula Liszt Ferenc \u2013 Ungv\u00e1ri L\u00e1szl\u00f3 Knorr, Schumann [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/27908\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T16:32:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/\",\"name\":\"Karnev\u00e1l -\",\"isPartOf\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\"},\"datePublished\":\"2021-09-28T19:58:16+00:00\",\"dateModified\":\"2026-05-26T16:32:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/radiojatek.elte.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karnev\u00e1l\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"name\":\"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151\",\"description\":\"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa\",\"publisher\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\"},\"alternateName\":\"Hangj\u00e1t\u00e9k-keres\u0151\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiojatek.elte.hu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\",\"name\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"contentUrl\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"width\":512,\"height\":512,\"caption\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\"},\"image\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karnev\u00e1l -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/27908\/","og_locale":"en_US","og_type":"article","og_title":"Karnev\u00e1l -","og_description":"1950. 05. 31. Kossuth 22.30 70 perc Robert Schumann zen\u00e9s \u00e9letrajza. Hangfelv\u00e9tel. \u00cdrta: Krist\u00f3f K\u00e1roly Rendezte: Sz\u00e9csi Ferenc K\u00f6zrem\u0171k\u00f6dik: Seb\u0151k Gy\u00f6rgy (zongora) Szereposzt\u00e1s: Robert Schumann \u2013 Ungv\u00e1ri L\u00e1szl\u00f3 Fridrich Wieck \u2013 R\u00e1tkay M\u00e1rton Kl\u00e1ra, a le\u00e1nya- Ruttkay \u00c9va Ernestine Flecken \u2013 B\u00e1nki Zsuzsa Hasslinger, zenem\u0171kiad\u00f3 \u2013 Justh Gyula Liszt Ferenc \u2013 Ungv\u00e1ri L\u00e1szl\u00f3 Knorr, Schumann [&hellip;]","og_url":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/27908\/","article_modified_time":"2026-05-26T16:32:00+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/","url":"https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/","name":"Karnev\u00e1l -","isPartOf":{"@id":"https:\/\/radiojatek.elte.hu\/#website"},"datePublished":"2021-09-28T19:58:16+00:00","dateModified":"2026-05-26T16:32:00+00:00","breadcrumb":{"@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/27908\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radiojatek.elte.hu\/"},{"@type":"ListItem","position":2,"name":"Karnev\u00e1l"}]},{"@type":"WebSite","@id":"https:\/\/radiojatek.elte.hu\/#website","url":"https:\/\/radiojatek.elte.hu\/","name":"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151","description":"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa","publisher":{"@id":"https:\/\/radiojatek.elte.hu\/#organization"},"alternateName":"Hangj\u00e1t\u00e9k-keres\u0151","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiojatek.elte.hu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/radiojatek.elte.hu\/#organization","name":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis","url":"https:\/\/radiojatek.elte.hu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/","url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","contentUrl":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","width":512,"height":512,"caption":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis"},"image":{"@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/27908"}],"collection":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay"}],"about":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/types\/radioplay"}],"author":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/comments?post=27908"}],"version-history":[{"count":2,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/27908\/revisions"}],"predecessor-version":[{"id":52037,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/27908\/revisions\/52037"}],"wp:attachment":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/media?parent=27908"}],"wp:term":[{"taxonomy":"radioplay_author","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_author?post=27908"},{"taxonomy":"radioplay_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_director?post=27908"},{"taxonomy":"radioplay_actor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_actor?post=27908"},{"taxonomy":"radioplay_award","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_award?post=27908"},{"taxonomy":"radioplay_category","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_category?post=27908"},{"taxonomy":"radioplay_translator","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_translator?post=27908"},{"taxonomy":"radioplay_dramaturge","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_dramaturge?post=27908"},{"taxonomy":"radioplay_radio_applier","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_radio_applier?post=27908"},{"taxonomy":"radioplay_codirector","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_codirector?post=27908"},{"taxonomy":"radioplay_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_editor?post=27908"},{"taxonomy":"radioplay_composer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_composer?post=27908"},{"taxonomy":"radioplay_music_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_editor?post=27908"},{"taxonomy":"radioplay_music_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_director?post=27908"},{"taxonomy":"radioplay_technical_colleague","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_technical_colleague?post=27908"},{"taxonomy":"radioplay_music_performer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_performer?post=27908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}