{"id":26981,"date":"2021-09-28T21:39:08","date_gmt":"2021-09-28T19:39:08","guid":{"rendered":"http:\/\/radiojatek.tld\/radiojatek\/26981\/"},"modified":"2026-05-26T18:33:34","modified_gmt":"2026-05-26T16:33:34","slug":"hangszerek-farsangja","status":"publish","type":"radioplay","link":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26981\/","title":{"rendered":"Hangszerek farsangja"},"content":{"rendered":"<p>Hangszerek farsangja \u2013 Egy kis muzsika, egy kis m\u00f3ka<\/p>\n<p>Sz\u00f6veg\u00e9t \u00e9s zen\u00e9j\u00e9t \u00edrta: Polg\u00e1r Tibor<\/p>\n<p>Rendezi: B\u00f6hm L\u00e1szl\u00f3<\/p>\n<p>Szerepl\u0151k: R\u00e1di\u00f3bemond\u00f3 \u2013 B\u00e1n Gy\u00f6rgy; Zongorista \u2013 B\u00e1rdi Gy\u00f6rgy; Wagner-rajong\u00f3 \u2013 K\u00e9sm\u00e1rki K\u00e1lm\u00e1n; R\u00e1di\u00f3port\u00e1s \u2013 Szalay P\u00e1l; R\u00e1di\u00f3rendez\u0151 \u2013 Kov\u00e1ch Alad\u00e1r; Heged\u0171m\u0171v\u00e9sz \u2013 P\u00e1rtos G\u00e9za; Oktat\u00f3 b\u00e1csi \u2013 Sug\u00e1r Lajos; Sanyika \u2013 Pethes S\u00e1ndor; Pluh\u00e1r \u2013 Pluh\u00e1r Istv\u00e1n<\/p>\n<p>1946. 03. 05. 18:45 (75 perc)<\/p>","protected":false},"excerpt":{"rendered":"<p>Hangszerek farsangja \u2013 Egy kis muzsika, egy kis m\u00f3ka Sz\u00f6veg\u00e9t \u00e9s zen\u00e9j\u00e9t \u00edrta: Polg\u00e1r Tibor Rendezi: B\u00f6hm L\u00e1szl\u00f3 Szerepl\u0151k: R\u00e1di\u00f3bemond\u00f3 \u2013 B\u00e1n Gy\u00f6rgy; Zongorista \u2013 B\u00e1rdi Gy\u00f6rgy; Wagner-rajong\u00f3 \u2013 K\u00e9sm\u00e1rki K\u00e1lm\u00e1n; R\u00e1di\u00f3port\u00e1s \u2013 Szalay P\u00e1l; R\u00e1di\u00f3rendez\u0151 \u2013 Kov\u00e1ch Alad\u00e1r; Heged\u0171m\u0171v\u00e9sz \u2013 P\u00e1rtos G\u00e9za; Oktat\u00f3 b\u00e1csi \u2013 Sug\u00e1r Lajos; Sanyika \u2013 Pethes S\u00e1ndor; Pluh\u00e1r \u2013 Pluh\u00e1r [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","radioplay_author":[7480,10664],"radioplay_director":[14452,7482],"radioplay_actor":[35142,16116,21730,21399,16352,30569,18025],"radioplay_award":[],"radioplay_category":[],"radioplay_translator":[],"radioplay_dramaturge":[],"radioplay_radio_applier":[],"radioplay_codirector":[],"radioplay_editor":[],"radioplay_composer":[17806],"radioplay_music_editor":[],"radioplay_music_director":[],"radioplay_technical_colleague":[],"radioplay_music_performer":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hangszerek farsangja -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26981\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hangszerek farsangja -\" \/>\n<meta property=\"og:description\" content=\"Hangszerek farsangja \u2013 Egy kis muzsika, egy kis m\u00f3ka Sz\u00f6veg\u00e9t \u00e9s zen\u00e9j\u00e9t \u00edrta: Polg\u00e1r Tibor Rendezi: B\u00f6hm L\u00e1szl\u00f3 Szerepl\u0151k: R\u00e1di\u00f3bemond\u00f3 \u2013 B\u00e1n Gy\u00f6rgy; Zongorista \u2013 B\u00e1rdi Gy\u00f6rgy; Wagner-rajong\u00f3 \u2013 K\u00e9sm\u00e1rki K\u00e1lm\u00e1n; R\u00e1di\u00f3port\u00e1s \u2013 Szalay P\u00e1l; R\u00e1di\u00f3rendez\u0151 \u2013 Kov\u00e1ch Alad\u00e1r; Heged\u0171m\u0171v\u00e9sz \u2013 P\u00e1rtos G\u00e9za; Oktat\u00f3 b\u00e1csi \u2013 Sug\u00e1r Lajos; Sanyika \u2013 Pethes S\u00e1ndor; Pluh\u00e1r \u2013 Pluh\u00e1r [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26981\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T16:33:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/\",\"name\":\"Hangszerek farsangja -\",\"isPartOf\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\"},\"datePublished\":\"2021-09-28T19:39:08+00:00\",\"dateModified\":\"2026-05-26T16:33:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/radiojatek.elte.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hangszerek farsangja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"name\":\"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151\",\"description\":\"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa\",\"publisher\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\"},\"alternateName\":\"Hangj\u00e1t\u00e9k-keres\u0151\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiojatek.elte.hu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\",\"name\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"contentUrl\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"width\":512,\"height\":512,\"caption\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\"},\"image\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hangszerek farsangja -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26981\/","og_locale":"en_US","og_type":"article","og_title":"Hangszerek farsangja -","og_description":"Hangszerek farsangja \u2013 Egy kis muzsika, egy kis m\u00f3ka Sz\u00f6veg\u00e9t \u00e9s zen\u00e9j\u00e9t \u00edrta: Polg\u00e1r Tibor Rendezi: B\u00f6hm L\u00e1szl\u00f3 Szerepl\u0151k: R\u00e1di\u00f3bemond\u00f3 \u2013 B\u00e1n Gy\u00f6rgy; Zongorista \u2013 B\u00e1rdi Gy\u00f6rgy; Wagner-rajong\u00f3 \u2013 K\u00e9sm\u00e1rki K\u00e1lm\u00e1n; R\u00e1di\u00f3port\u00e1s \u2013 Szalay P\u00e1l; R\u00e1di\u00f3rendez\u0151 \u2013 Kov\u00e1ch Alad\u00e1r; Heged\u0171m\u0171v\u00e9sz \u2013 P\u00e1rtos G\u00e9za; Oktat\u00f3 b\u00e1csi \u2013 Sug\u00e1r Lajos; Sanyika \u2013 Pethes S\u00e1ndor; Pluh\u00e1r \u2013 Pluh\u00e1r [&hellip;]","og_url":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26981\/","article_modified_time":"2026-05-26T16:33:34+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/","url":"https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/","name":"Hangszerek farsangja -","isPartOf":{"@id":"https:\/\/radiojatek.elte.hu\/#website"},"datePublished":"2021-09-28T19:39:08+00:00","dateModified":"2026-05-26T16:33:34+00:00","breadcrumb":{"@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/26981\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radiojatek.elte.hu\/"},{"@type":"ListItem","position":2,"name":"Hangszerek farsangja"}]},{"@type":"WebSite","@id":"https:\/\/radiojatek.elte.hu\/#website","url":"https:\/\/radiojatek.elte.hu\/","name":"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151","description":"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa","publisher":{"@id":"https:\/\/radiojatek.elte.hu\/#organization"},"alternateName":"Hangj\u00e1t\u00e9k-keres\u0151","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiojatek.elte.hu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/radiojatek.elte.hu\/#organization","name":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis","url":"https:\/\/radiojatek.elte.hu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/","url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","contentUrl":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","width":512,"height":512,"caption":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis"},"image":{"@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/26981"}],"collection":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay"}],"about":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/types\/radioplay"}],"author":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/comments?post=26981"}],"version-history":[{"count":3,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/26981\/revisions"}],"predecessor-version":[{"id":67054,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/26981\/revisions\/67054"}],"wp:attachment":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/media?parent=26981"}],"wp:term":[{"taxonomy":"radioplay_author","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_author?post=26981"},{"taxonomy":"radioplay_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_director?post=26981"},{"taxonomy":"radioplay_actor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_actor?post=26981"},{"taxonomy":"radioplay_award","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_award?post=26981"},{"taxonomy":"radioplay_category","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_category?post=26981"},{"taxonomy":"radioplay_translator","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_translator?post=26981"},{"taxonomy":"radioplay_dramaturge","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_dramaturge?post=26981"},{"taxonomy":"radioplay_radio_applier","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_radio_applier?post=26981"},{"taxonomy":"radioplay_codirector","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_codirector?post=26981"},{"taxonomy":"radioplay_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_editor?post=26981"},{"taxonomy":"radioplay_composer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_composer?post=26981"},{"taxonomy":"radioplay_music_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_editor?post=26981"},{"taxonomy":"radioplay_music_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_director?post=26981"},{"taxonomy":"radioplay_technical_colleague","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_technical_colleague?post=26981"},{"taxonomy":"radioplay_music_performer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_performer?post=26981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}