{"id":26162,"date":"2021-09-28T21:21:15","date_gmt":"2021-09-28T19:21:15","guid":{"rendered":"http:\/\/radiojatek.tld\/radiojatek\/26162\/"},"modified":"2026-03-08T17:09:40","modified_gmt":"2026-03-08T16:09:40","slug":"elso-rollerkiralyno","status":"publish","type":"radioplay","link":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26162\/","title":{"rendered":"Els\u0151 Rollerkir\u00e1lyn\u0151"},"content":{"rendered":"<p>Jan Werich mes\u00e9j\u00e9t r\u00e1di\u00f3ra alkalmazta: Helena Sykorov\u00e1<\/p>\n<p>Ford\u00edtotta: Bojt\u00e1r Endre<\/p>\n<p>Zen\u00e9j\u00e9t Jaroslav Jezek mot\u00edvumainak felhaszn\u00e1l\u00e1s\u00e1val Jiri Bazant \u00edrta<\/p>\n<p>Zenei munkat\u00e1rs: T\u00f6r\u00f6k Etel<\/p>\n<p>A felv\u00e9telt N\u00e9meth Zolt\u00e1n \u00e9s K\u00f3nya Csaba k\u00e9sz\u00edtette<\/p>\n<p>A rendez\u0151 munkat\u00e1rsa: Bereczky S\u00e1ndor<\/p>\n<p>Szerkeszt\u0151: Szeb\u00e9nyi Cec\u00edlia<\/p>\n<p>T\u00e1rsrendez\u0151: Vars\u00e1nyi Anik\u00f3<\/p>\n<p>Rendezte: Karel Weinlich, a Pr\u00e1gai R\u00e1di\u00f3 rendez\u0151je<\/p>\n<p>Szerepl\u0151k: Mes\u00e9l\u0151 &#8211; L\u00e1ng J\u00f3zsef; Zdenicka &#8211; Herczeg Csilla; Jani kir\u00e1ly &#8211; R\u00e1t\u00f3ti Zolt\u00e1n; Hal\u00e1sz &#8211; Hark\u00e1nyi Endre; A feles\u00e9ge &#8211; Cs\u0171r\u00f6s Karola; Moln\u00e1r &#8211; S. T\u00f3th J\u00f3zsef; Tan\u00e1csos &#8211; Raks\u00e1nyi Gell\u00e9rt; A kir\u00e1ly n\u00e9nik\u00e9je &#8211; Gyarmathy Anik\u00f3.<\/p>\n<p>K\u00f6zrem\u0171k\u00f6d\u00f6tt: Beregi P\u00e9ter, Kutas J\u00f3zsef, Leisen Antal; ifj. Path\u00f3 Istv\u00e1n \u00e9s Tordai G\u00e1bor.<\/p>\n<p>Bemutat\u00f3: 1987. 03. 22. 8:05-8:47 Pet\u0151fi.<\/p>\n<p>Ism\u00e9tl\u00e9sek: 1990. 01. 04. 16:15-17:00 Kossuth, 1991. 09. 22. 8:10-8:52 Pet\u0151fi, 2005. 07. 10. 13:16-13:58 Pet\u0151fi.<\/p>","protected":false},"excerpt":{"rendered":"<p>Jan Werich mes\u00e9j\u00e9t r\u00e1di\u00f3ra alkalmazta: Helena Sykorov\u00e1 Ford\u00edtotta: Bojt\u00e1r Endre Zen\u00e9j\u00e9t Jaroslav Jezek mot\u00edvumainak felhaszn\u00e1l\u00e1s\u00e1val Jiri Bazant \u00edrta Zenei munkat\u00e1rs: T\u00f6r\u00f6k Etel A felv\u00e9telt N\u00e9meth Zolt\u00e1n \u00e9s K\u00f3nya Csaba k\u00e9sz\u00edtette A rendez\u0151 munkat\u00e1rsa: Bereczky S\u00e1ndor Szerkeszt\u0151: Szeb\u00e9nyi Cec\u00edlia T\u00e1rsrendez\u0151: Vars\u00e1nyi Anik\u00f3 Rendezte: Karel Weinlich, a Pr\u00e1gai R\u00e1di\u00f3 rendez\u0151je Szerepl\u0151k: Mes\u00e9l\u0151 &#8211; L\u00e1ng J\u00f3zsef; Zdenicka &#8211; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","radioplay_author":[7785,11324],"radioplay_director":[8793,11325],"radioplay_actor":[21262,16103,21251,15706,33677,29135,18334,17583,15718,19857,15671,33667],"radioplay_award":[],"radioplay_category":[15630],"radioplay_translator":[18391],"radioplay_dramaturge":[],"radioplay_radio_applier":[11326],"radioplay_codirector":[8348],"radioplay_editor":[8513],"radioplay_composer":[],"radioplay_music_editor":[16736],"radioplay_music_director":[],"radioplay_technical_colleague":[17774,16263],"radioplay_music_performer":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Els\u0151 Rollerkir\u00e1lyn\u0151 -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26162\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Els\u0151 Rollerkir\u00e1lyn\u0151 -\" \/>\n<meta property=\"og:description\" content=\"Jan Werich mes\u00e9j\u00e9t r\u00e1di\u00f3ra alkalmazta: Helena Sykorov\u00e1 Ford\u00edtotta: Bojt\u00e1r Endre Zen\u00e9j\u00e9t Jaroslav Jezek mot\u00edvumainak felhaszn\u00e1l\u00e1s\u00e1val Jiri Bazant \u00edrta Zenei munkat\u00e1rs: T\u00f6r\u00f6k Etel A felv\u00e9telt N\u00e9meth Zolt\u00e1n \u00e9s K\u00f3nya Csaba k\u00e9sz\u00edtette A rendez\u0151 munkat\u00e1rsa: Bereczky S\u00e1ndor Szerkeszt\u0151: Szeb\u00e9nyi Cec\u00edlia T\u00e1rsrendez\u0151: Vars\u00e1nyi Anik\u00f3 Rendezte: Karel Weinlich, a Pr\u00e1gai R\u00e1di\u00f3 rendez\u0151je Szerepl\u0151k: Mes\u00e9l\u0151 &#8211; L\u00e1ng J\u00f3zsef; Zdenicka &#8211; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26162\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-08T16:09:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/\",\"name\":\"Els\u0151 Rollerkir\u00e1lyn\u0151 -\",\"isPartOf\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\"},\"datePublished\":\"2021-09-28T19:21:15+00:00\",\"dateModified\":\"2026-03-08T16:09:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/radiojatek.elte.hu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Els\u0151 Rollerkir\u00e1lyn\u0151\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#website\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"name\":\"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151\",\"description\":\"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa\",\"publisher\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\"},\"alternateName\":\"Hangj\u00e1t\u00e9k-keres\u0151\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/radiojatek.elte.hu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#organization\",\"name\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\",\"url\":\"https:\/\/radiojatek.elte.hu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"contentUrl\":\"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg\",\"width\":512,\"height\":512,\"caption\":\"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis\"},\"image\":{\"@id\":\"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Els\u0151 Rollerkir\u00e1lyn\u0151 -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26162\/","og_locale":"en_US","og_type":"article","og_title":"Els\u0151 Rollerkir\u00e1lyn\u0151 -","og_description":"Jan Werich mes\u00e9j\u00e9t r\u00e1di\u00f3ra alkalmazta: Helena Sykorov\u00e1 Ford\u00edtotta: Bojt\u00e1r Endre Zen\u00e9j\u00e9t Jaroslav Jezek mot\u00edvumainak felhaszn\u00e1l\u00e1s\u00e1val Jiri Bazant \u00edrta Zenei munkat\u00e1rs: T\u00f6r\u00f6k Etel A felv\u00e9telt N\u00e9meth Zolt\u00e1n \u00e9s K\u00f3nya Csaba k\u00e9sz\u00edtette A rendez\u0151 munkat\u00e1rsa: Bereczky S\u00e1ndor Szerkeszt\u0151: Szeb\u00e9nyi Cec\u00edlia T\u00e1rsrendez\u0151: Vars\u00e1nyi Anik\u00f3 Rendezte: Karel Weinlich, a Pr\u00e1gai R\u00e1di\u00f3 rendez\u0151je Szerepl\u0151k: Mes\u00e9l\u0151 &#8211; L\u00e1ng J\u00f3zsef; Zdenicka &#8211; [&hellip;]","og_url":"https:\/\/radiojatek.elte.hu\/eng\/radiojatek\/26162\/","article_modified_time":"2026-03-08T16:09:40+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/","url":"https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/","name":"Els\u0151 Rollerkir\u00e1lyn\u0151 -","isPartOf":{"@id":"https:\/\/radiojatek.elte.hu\/#website"},"datePublished":"2021-09-28T19:21:15+00:00","dateModified":"2026-03-08T16:09:40+00:00","breadcrumb":{"@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/radiojatek.elte.hu\/radiojatek\/26162\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/radiojatek.elte.hu\/"},{"@type":"ListItem","position":2,"name":"Els\u0151 Rollerkir\u00e1lyn\u0151"}]},{"@type":"WebSite","@id":"https:\/\/radiojatek.elte.hu\/#website","url":"https:\/\/radiojatek.elte.hu\/","name":"R\u00e1di\u00f3j\u00e1t\u00e9k-keres\u0151","description":"Magyar hangj\u00e1t\u00e9kok, r\u00e1di\u00f3j\u00e1t\u00e9kok, dokumentumj\u00e1t\u00e9kok, mesej\u00e1t\u00e9kok adatb\u00e1zisa","publisher":{"@id":"https:\/\/radiojatek.elte.hu\/#organization"},"alternateName":"Hangj\u00e1t\u00e9k-keres\u0151","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radiojatek.elte.hu\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/radiojatek.elte.hu\/#organization","name":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis","url":"https:\/\/radiojatek.elte.hu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/","url":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","contentUrl":"https:\/\/radiojatek.elte.hu\/wp-content\/uploads\/2025\/10\/cropped-kereso_kocka.jpg","width":512,"height":512,"caption":"Magyar r\u00e1di\u00f3j\u00e1t\u00e9k adatb\u00e1zis"},"image":{"@id":"https:\/\/radiojatek.elte.hu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/26162"}],"collection":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay"}],"about":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/types\/radioplay"}],"author":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/comments?post=26162"}],"version-history":[{"count":3,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/26162\/revisions"}],"predecessor-version":[{"id":59364,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay\/26162\/revisions\/59364"}],"wp:attachment":[{"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/media?parent=26162"}],"wp:term":[{"taxonomy":"radioplay_author","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_author?post=26162"},{"taxonomy":"radioplay_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_director?post=26162"},{"taxonomy":"radioplay_actor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_actor?post=26162"},{"taxonomy":"radioplay_award","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_award?post=26162"},{"taxonomy":"radioplay_category","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_category?post=26162"},{"taxonomy":"radioplay_translator","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_translator?post=26162"},{"taxonomy":"radioplay_dramaturge","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_dramaturge?post=26162"},{"taxonomy":"radioplay_radio_applier","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_radio_applier?post=26162"},{"taxonomy":"radioplay_codirector","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_codirector?post=26162"},{"taxonomy":"radioplay_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_editor?post=26162"},{"taxonomy":"radioplay_composer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_composer?post=26162"},{"taxonomy":"radioplay_music_editor","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_editor?post=26162"},{"taxonomy":"radioplay_music_director","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_director?post=26162"},{"taxonomy":"radioplay_technical_colleague","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_technical_colleague?post=26162"},{"taxonomy":"radioplay_music_performer","embeddable":true,"href":"https:\/\/radiojatek.elte.hu\/eng\/wp-json\/wp\/v2\/radioplay_music_performer?post=26162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}